{"id":2233,"date":"2020-01-30T10:56:39","date_gmt":"2020-01-30T09:56:39","guid":{"rendered":"http:\/\/urbanistes.be\/cub\/?p=2233"},"modified":"2020-01-30T16:25:00","modified_gmt":"2020-01-30T15:25:00","slug":"colloque-uclouvain-loci-mardi-11-02-2020-louvain-la-neuve-a-la-croisee-des-chemins","status":"publish","type":"post","link":"https:\/\/urbanistes.be\/cub\/colloque-uclouvain-loci-mardi-11-02-2020-louvain-la-neuve-a-la-croisee-des-chemins\/","title":{"rendered":"Colloque UCLOUVAIN\/LOCI Mardi 11\/02\/2020 LOUVAIN LA NEUVE \u00e0 la crois\u00e9e des chemins"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1027\" src=\"http:\/\/urbanistes.be\/fup\/wp-content\/uploads\/2020\/01\/colloque3.png\" alt=\"\" width=\"1061\" height=\"331\" \/><\/p>\n<div style=\"text-align: center;\"><strong><u>COUT ET PARTICIPATION <\/u><\/strong><\/div>\n<p style=\"text-align: center;\"><strong>Co\u00fbt : 80 \u20ac comprenant la participation au colloque, l\u2019ouvrage, l\u2019ouvrage pr\u00e9c\u00e9dent auquel ont contribu\u00e9 les m\u00eames auteurs, le lunch, la pause et le drink final. Les inscriptions seront cl\u00f4tur\u00e9es le 6\/2. Le paiement confirme l\u2019inscription (40 places, attribu\u00e9es dans l\u2019ordre de r\u00e9ception des paiements).<\/strong><\/p>\n<p style=\"text-align: center;\">Lien vers le programme et l\u2019inscription : <a href=\"http:\/\/urbanistes.be\/fup\/wp-content\/uploads\/2020\/01\/LLN-COLLOQUE-LOCI-prospectus2-200120-final.pdf\">COLLOQUE UCLOUVAIN\/LOCI<\/a><\/p>\n<p>Le plan directeur, que le Groupe Urbanisme Architecture (Groupe UA) a con\u00e7u au moment de la cr\u00e9ation de Louvain-La-Neuve, reste un demi-si\u00e8cle plus tard, le cadre du d\u00e9veloppement de la ville universitaire.<\/p>\n<p>La personnalit\u00e9 de Raymond Lemaire joua un r\u00f4le d\u00e9cisif dans l\u2019orientation culturaliste du projet, c\u2019est-\u00e0-dire la r\u00e9f\u00e9rence \u00e0 l\u2019histoire urbaine et le respect du site.<\/p>\n<p>Le Groupe Urbanisme Architecture a notamment mis l\u2019accent sur la dimension humaine de l\u2019aire urbaine centrale\u00a0; priorit\u00e9 \u00e0 la circulation pi\u00e9tonne, pr\u00e9servation de la qualit\u00e9 de l\u2019air et de l\u2019eau, absence de carburants fossiles pour le chauffage, abondance d\u2019espaces publics arbor\u00e9s, s\u00e9paration de la propri\u00e9t\u00e9 du sol et celle des b\u00e2timents. Toutefois, divers investissements pr\u00e9vus vont aire passer Louvain-La-Neuve \u00e0 un nouveau stade de \u00ab\u00a0maturit\u00e9 urbaine\u00a0\u00bb d\u2019o\u00f9 le titre.<\/p>\n<p>Le site universitaire est devenu un espace convoit\u00e9. Le moment est dangereux. Il faut se montrer s\u00e9lectif parmi les opportunit\u00e9s qui se pr\u00e9sentent. Ce discernement est indispensable si l\u2019on veut garder le cap et poursuivre l\u2019\u0153uvre dont le Groupe UA a donn\u00e9 l\u2019impulsion primordiale.<\/p>\n<p>Cet ouvrage compl\u00e8te l\u2019ouvrage \u00ab La recherche de la qualit\u00e9 environnementale et urbaine : le cas de Louvain-La-Neuve (Belgique), \u00e9ditions du CERTU, Lyon 2009, auquel ont contribu\u00e9 les m\u00eames auteurs.<\/p>\n<a href=\"https:\/\/urbanistes.be\/cub\/wp-content\/uploads\/2020\/01\/LLN-COLLOQUE-LOCI-prospectus2-200120-final.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">LLN-COLLOQUE-LOCI-prospectus2-200120-final<\/a>\n","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">COUT ET PARTICIPATION Co\u00fbt : 80 \u20ac comprenant la participation au colloque, l\u2019ouvrage, l\u2019ouvrage pr\u00e9c\u00e9dent auquel ont contribu\u00e9 les m\u00eames auteurs, le lunch, la pause et le drink final. Les&hellip;<\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"views":4056,"_links":{"self":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts\/2233"}],"collection":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/comments?post=2233"}],"version-history":[{"count":2,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts\/2233\/revisions"}],"predecessor-version":[{"id":2236,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts\/2233\/revisions\/2236"}],"wp:attachment":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/media?parent=2233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/categories?post=2233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/tags?post=2233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}