{"id":1754,"date":"2018-03-27T09:46:11","date_gmt":"2018-03-27T07:46:11","guid":{"rendered":"http:\/\/urbanistes.be\/cub\/?p=1754"},"modified":"2018-03-27T09:46:11","modified_gmt":"2018-03-27T07:46:11","slug":"forum-des-projets-urbains","status":"publish","type":"post","link":"https:\/\/urbanistes.be\/cub\/forum-des-projets-urbains\/","title":{"rendered":"Forum des projets urbains"},"content":{"rendered":"<p><a class=\"typeh1\" href=\"http:\/\/www.projetsurbains.com\/go\/comment-participer-forum-projets-urbains.html\">Inscrivez-vous au Forum des Projets Urbains du Grand Ouest 2018<\/a><\/p>\n<p><a href=\"http:\/\/www.projetsurbains.com\/go\/\" target=\"_blank\" rel=\"noopener\">Lien vers le site<\/a><\/p>\n<h2>Comment participer au Forum ?<\/h2>\n<div class=\"corps_texte\">\n<h3 class=\"orange\">Conditions de participation<\/h3>\n<p><strong>Quel est le co\u00fbt de la participation au FPU GO ?<\/strong><\/p>\n<p>PROFITEZ DE NOS TARIFS D\u00c9GRESSIFS<\/p>\n<p><span class=\"moyen\">260.00\u20ac HT (soit 312.00\u20ac TTC)<\/span><br \/>\nPour une entr\u00e9e participant au Forum<\/p>\n<p><span class=\"moyen\">240.00\u20ac HT (soit 288.00\u20ac TTC)<\/span><br \/>\nA partir du deuxi\u00e8me participant au Forum pour une m\u00eame commande ou pour une soci\u00e9t\u00e9 d\u00e9j\u00e0 factur\u00e9e<\/p>\n<p><span class=\"moyen\">220.00\u20ac HT (soit 264.00\u20ac TTC)<\/span><br \/>\nA partir du sixi\u00e8me participant au Forum pour une m\u00eame commande ou pour une soci\u00e9t\u00e9 d\u00e9j\u00e0 factur\u00e9e<\/p>\n<p><strong>Que comprend le co\u00fbt d\u2019inscription au FPU GO ?<\/strong><\/p>\n<ul>\n<li>la participation aux ateliers et aux programmes de la journ\u00e9e,<\/li>\n<li>le d\u00e9jeuner et les pauses \/ boissons,<\/li>\n<li>une information r\u00e9guli\u00e8re et compl\u00e8te sur le programme, les projets, etc,<\/li>\n<li>l\u2019acc\u00e8s \u00e0 l\u2019espace membres du site avec notamment la possibilit\u00e9 de consulter les projets, l\u2019annuaire des participants et de pr\u00e9voir ses rendez-vous et son programme de la journ\u00e9e \u00e0 l\u2019avance.<\/li>\n<\/ul>\n<p>Afin de b\u00e9n\u00e9ficier de l&#8217;ensemble des services du site d\u00e8s leurs mises en ligne, nous vous invitons \u00e0 vous inscrire d\u00e8s aujourd&#8217;hui au Forum, en remplissant\u00a0<a href=\"http:\/\/www.projetsurbains.com\/go\/login\">le formulaire d\u2019inscription en ligne.<\/a><\/p>\n<p><strong>Informations suppl\u00e9mentaires et\/ou convention de formation<\/strong>\u00a0:<\/p>\n<ul>\n<li>Email :\u00a0<a href=\"mailto:go@projetsurbains.com?subject=Renseignement%20Forum%20des%20Projets%20Urbains%20GO\">go@projetsurbains.com<\/a><\/li>\n<li>T\u00e9l : 01 48 24 81 27<\/li>\n<\/ul>\n<h3 class=\"orange\">Inscription en ligne<\/h3>\n<p>Pour s\u2019inscrire comme participant, la d\u00e9marche est simple et se d\u00e9roule en trois \u00e9tapes :<\/p>\n<ul>\n<li><strong>Etape n\u00b01<\/strong>\u00a0: Remplissez\u00a0<a href=\"http:\/\/www.projetsurbains.com\/go\/login\">le formulaire d\u2019inscription en ligne<\/a>, et validez d\u2019un seul clic votre inscription.<\/li>\n<li><strong>Etape n\u00b02<\/strong>\u00a0: Vous serez ensuite invit\u00e9 \u00e0 imprimer votre formulaire d&#8217;inscription et \u00e0 nous la retourner compl\u00e9t\u00e9e de votre r\u00e8glement ou, pour les collectivit\u00e9s et les administrations, possibilit\u00e9 de r\u00e8glement par mandat administratif \u00e0 r\u00e9ception de facture.<\/li>\n<li><strong>Etape n\u00b03<\/strong>\u00a0: D\u00e8s r\u00e9ception de votre r\u00e8glement, nous vous ferons parvenir une facture acquitt\u00e9e. Cette facture tiendra lieu d&#8217;accus\u00e9 de r\u00e9ception. Vous recevrez \u00e9galement \u00e0 l&#8217;adresse e-mail que vous nous aurez indiqu\u00e9e, un identifiant et un mot de passe vous permettant d&#8217;acc\u00e9der\u00a0<strong>aux services de l&#8217;espace membres<\/strong>\u00a0du site internet, avec une confirmation de votre inscription.<\/li>\n<\/ul>\n<p><strong>Attention : les badges d&#8217;entr\u00e9es nominatifs vous seront envoy\u00e9s par mail dans les 15 jours qui pr\u00e9c\u00e8dent le forum.<br \/>\n<\/strong><\/p>\n<p><center><a class=\"lien_suite_rect\" href=\"http:\/\/www.projetsurbains.com\/go\/login\">INSCRIPTION EN LIGNE<\/a><\/center><\/p>\n<h3 class=\"orange\">Inscription sur le formulaire papier<\/h3>\n<p>Vous pouvez \u00e9galement vous inscrire en t\u00e9l\u00e9chargeant la plaquette ci-dessous et en nous renvoyant le bulletin d&#8217;inscription qui se trouve \u00e0 la fin du document. Une fois compl\u00e9t\u00e9, il vous suffit de nous le retourner accompagn\u00e9 de votre r\u00e8glement \u00e0 l&#8217;adresse ci-dessous :<\/p>\n<p><strong>INNOVAPRESSE<br \/>\nForum des Projets Urbains<br \/>\n5 rue Saulnier<br \/>\n75009 PARIS<br \/>\n<\/strong><\/p>\n<p><center><a class=\"lien_suite_rect\" href=\"http:\/\/www.projetsurbains.com\/go\/FPUGO2017_inscription.pdf\" target=\"_blank\" rel=\"noopener\">T\u00c9L\u00c9CHARGER LE FORMULAIRE<\/a><\/center><\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Inscrivez-vous au Forum des Projets Urbains du Grand Ouest 2018 Lien vers le site Comment participer au Forum ? Conditions de participation Quel est le co\u00fbt de la participation au&hellip;<\/div>\n","protected":false},"author":1,"featured_media":1756,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"views":3073,"_links":{"self":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts\/1754"}],"collection":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/comments?post=1754"}],"version-history":[{"count":1,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts\/1754\/revisions"}],"predecessor-version":[{"id":1757,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts\/1754\/revisions\/1757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/media\/1756"}],"wp:attachment":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/media?parent=1754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/categories?post=1754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/tags?post=1754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}