{"id":1332,"date":"2017-09-05T16:04:04","date_gmt":"2017-09-05T14:04:04","guid":{"rendered":"http:\/\/urbanistes.be\/cub\/?p=1332"},"modified":"2017-09-05T16:04:04","modified_gmt":"2017-09-05T14:04:04","slug":"conseillerere-en-amenagement-du-territoire-et-urbanisme-ff-service-amenagement-du-territoire-et-urbanisme-ville-de-mouscron","status":"publish","type":"post","link":"https:\/\/urbanistes.be\/cub\/conseillerere-en-amenagement-du-territoire-et-urbanisme-ff-service-amenagement-du-territoire-et-urbanisme-ville-de-mouscron\/","title":{"rendered":"Conseiller(\u00e8re) en am\u00e9nagement du territoire et urbanisme ff &#8211; service am\u00e9nagement du territoire et urbanisme &#8211; VILLE DE MOUSCRON"},"content":{"rendered":"<h3><strong>1. Emploi :<\/strong><\/h3>\n<p>Conseiller(\u00e8re) en am\u00e9nagement du territoire et urbanisme pour le service<br \/>\nam\u00e9nagement du territoire et urbanisme de la Ville de Mouscron.<\/p>\n<h3><strong>2. Description de la fonction :<\/strong><\/h3>\n<p><strong>1. Objectifs et t\u00e2ches de l\u2019agent occupant la fonction<\/strong><br \/>\na) Suivre l\u2019orientation donn\u00e9e \u00e0 l\u2019organisation :<br \/>\n\uf0b7 Respecter les objectifs strat\u00e9giques et op\u00e9rationnels<br \/>\n\uf0b7 Suivre un cadre de valeurs, incluant la transparence, l\u2019\u00e9thique et le sens du service au citoyen, et un code de conduite tels que d\u00e9finis par l\u2019organisation ;<br \/>\nb) Suivre le syst\u00e8me de management mis en place :<br \/>\n\uf0b7 Mettre en \u0153uvre, appliquer les proc\u00e9dures ;<br \/>\n\uf0b7 Suivre les objectifs individuels fix\u00e9s ;<br \/>\n\uf0b7 Ex\u00e9cuter de fa\u00e7on autonome le travail selon les priorit\u00e9s d\u00e9finies ;<br \/>\n\uf0b7 Se tenir inform\u00e9 de la l\u00e9gislation et autres normes de r\u00e9f\u00e9rences relatives \u00e0 la mati\u00e8re ;<br \/>\n\uf0b7 Suivre les formations jug\u00e9es utiles par la hi\u00e9rarchie ;<br \/>\nc) Se comporter de mani\u00e8re ad\u00e9quate :<br \/>\n\uf0b7 Agir en accord avec les objectifs et valeurs \u00e9tablis ;<br \/>\n\uf0b7 Aider ses coll\u00e8gues \u00e0 mener \u00e0 bien leurs t\u00e2ches et \u00e0 r\u00e9aliser leurs projets et objectifs en relation avec les objectifs de l\u2019organisation toute enti\u00e8re ;<br \/>\n\uf0b7 Formuler des propositions d\u2019innovation et d\u2019am\u00e9lioration et se montrer proactif dans la gestion des t\u00e2ches quotidiennes.<\/p>\n<p><strong>2. T\u00e2ches du bureau<\/strong><\/p>\n<p>a) Administration de l\u2019am\u00e9nagement du territoire : cr\u00e9ation et mise en \u0153uvre des outils d\u2019am\u00e9nagement strat\u00e9giques (Sch\u00e9ma d\u2019Orientation Local\u2013Guide Communal d\u2019Urbanisme\u2013Sch\u00e9ma de D\u00e9veloppement Communal-Site \u00e0 R\u00e9am\u00e9nager, \u2026) ;<br \/>\nb) Administration de l\u2019urbanisme : gestion des permis ;<br \/>\nc) Administration des permis d\u2019environnement et des permis unique : gestion des demandes de permis ;<br \/>\nd) Administration des permis d\u2019implantation commerciale et des permis int\u00e9gr\u00e9 : gestion des demandes de permis ;<br \/>\ne) Administration des demandes d\u2019enseigne et publicit\u00e9 ;<br \/>\nf) Administration de toute question touchant \u00e0 l\u2019am\u00e9nagement du territoire et \u00e0 l\u2019urbanisme.<\/p>\n<p><strong>3. T\u00e2ches sp\u00e9cifiques \u00e0 la fonction<\/strong><\/p>\n<p>a) Gestion des permis d\u2019environnement et des permis unique ;<br \/>\nb) Gestion des permis implantations commerciales et permis int\u00e9gr\u00e9 ;<br \/>\nc) Gestion des permis d\u2019urbanisation ;<br \/>\nd) Gestion des permis d\u2019urbanisme (art.127) ;<br \/>\ne) Traitement des dossiers relatifs aux outils d\u2019am\u00e9nagement strat\u00e9giques (SOL\u2013GCU\u2013SDC-SAR \u2026) ;<br \/>\nf) Suivre la formation Conseiller en Am\u00e9nagement du Territoire et Urbanisme ;<br \/>\ng) Assurer le suivi du courrier interne et externe ainsi que des mails internes et externes ;<br \/>\nh) Ma\u00eetriser les outils technologiques indispensables \u00e0 la bonne marche du service ;<br \/>\ni) Alimenter en donn\u00e9es le syst\u00e8me d\u2019information ;<br \/>\nj) Assister le responsable de service dans la r\u00e9alisation des missions ;<br \/>\nk) Informer, conseiller et assister les collaborateurs dans la r\u00e9alisation de leur travail ;<br \/>\nl) Aider \u00e0 pr\u00e9parer les dossiers Coll\u00e8ge-Conseil du service ;<br \/>\nm) Toutes autres t\u00e2ches du bureau, en fonction des besoins, et notamment \u00e0 assurer la continuit\u00e9 du service en cas d\u2019absences des coll\u00e8gues ;<br \/>\nn) Ex\u00e9cuter toutes les activit\u00e9s non sp\u00e9cifiques mais indispensables \u00e0 la qualit\u00e9 de la fonction et du service ;<br \/>\no) Assurer la coop\u00e9ration avec les autres unit\u00e9s.<\/p>\n<h3>3. Comp\u00e9tence et qualit\u00e9s requises :<\/h3>\n<p>1. Poss\u00e9der un dipl\u00f4me de l\u2019enseignement universitaire (master) ou assimil\u00e9 (licenci\u00e9) : dipl\u00f4me d\u2019ing\u00e9nieur architecte, dipl\u00f4me d\u2019architecte, \u00eatre en possession d\u2019un master compl\u00e9mentaire en am\u00e9nagement du territoire et urbanisme, ou de tout dipl\u00f4me de niveau universitaire ou de l\u2019enseignement sup\u00e9rieur de type long qui comprend une formation d\u2019au moins 10 cr\u00e9dits dans le domaine de l\u2019am\u00e9nagement du territoire et de l\u2019urbanisme ;<br \/>\n2. Poss\u00e9der une exp\u00e9rience professionnelle d\u2019une fonction similaire exerc\u00e9e au sein d\u2019un autre pouvoir local est un atout ;<br \/>\n3. Avoir une bonne expression orale et \u00e9crite ;<br \/>\n4. Etre rigoureux et bien organis\u00e9 : ordre et m\u00e9thode, respect des d\u00e9lais, choix des priorit\u00e9s\u2026 ;<br \/>\n5. Poss\u00e9der un sens de l\u2019analyse et un esprit de synth\u00e8se ;<br \/>\n6. Avoir une bonne ma\u00eetrise des outils informatiques (Word, Excel, Access, Arcgis, logiciel urbanistique type urbaweb\/urban, \u2026) ;<br \/>\n7. S\u2019engager \u00e0 suivre la formation continue pour les conseillers en am\u00e9nagement du territoire et urbanisme.<\/p>\n<h3>4. Remise des candidatures :<\/h3>\n<p>Les candidatures, accompagn\u00e9es d\u2019une lettre de motivation, un curriculum vitae, un<br \/>\npasseport APE, un extrait de casier judiciaire et une copie de votre dipl\u00f4me sont \u00e0<br \/>\nenvoyer \u00e0 :<\/p>\n<p style=\"text-align: center;\"><strong>VILLE DE MOUSCRON<\/strong><br \/>\n<strong> SERVICE DU PERSONNEL<\/strong><br \/>\n<strong> A l\u2019attention de Mme TIBERGHIEN<\/strong><br \/>\n<strong> Rue de Courtrai, 63 \u2013 7700 Mouscron<\/strong><br \/>\n<strong> ou par mail \u00e0 :<\/strong><br \/>\n<a href=\"mailto:catherine.tiberghien@mouscron.be\"><strong> catherine.tiberghien@mouscron.be<\/strong><\/a><br \/>\n<strong> avant le 22\/09\/2017 \u00e0 16H00<\/strong><\/p>\n<h3>5. Divers\/renseignements compl\u00e9mentaires :<\/h3>\n<p>Bar\u00e8me : A1 \u2013 R.G.B. \u2013 Temps plein (37H30\/semaine).<br \/>\nTraitement mensuel brut d\u00e9but de carri\u00e8re : 3.072,47 \u20ac (\u00e0 l\u2019index actuel) avec en sus<br \/>\nla valorisation possible d\u2019une anciennet\u00e9 bar\u00e9mique selon les r\u00e8gles en vigueur.<br \/>\nToute pr\u00e9cision compl\u00e9mentaire concernant le poste \u00e0 pourvoir peut \u00eatre obtenue<br \/>\naupr\u00e8s de : Mme DEPLECHIN Laurence, Chef de Division ff, t\u00e9l. 056\/860.815 &#8211; Mail :<br \/>\n<a href=\"mailto:laurence.deplechin@mouscron.be\">laurence.deplechin@mouscron.be<\/a>.<br \/>\nLes candidat(e)s retenu(e)s seront invit\u00e9(e)s par courrier et\/ou par mail \u00e0 aux deux<br \/>\npremi\u00e8res \u00e9preuves \u00e9crites qui auront lieu le lundi 02\/10\/2017 \u00e0 8H30.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">1. Emploi : Conseiller(\u00e8re) en am\u00e9nagement du territoire et urbanisme pour le service am\u00e9nagement du territoire et urbanisme de la Ville de Mouscron. 2. Description de la fonction : 1.&hellip;<\/div>\n","protected":false},"author":1,"featured_media":1333,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"views":6343,"_links":{"self":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts\/1332"}],"collection":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/comments?post=1332"}],"version-history":[{"count":1,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts\/1332\/revisions"}],"predecessor-version":[{"id":1334,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/posts\/1332\/revisions\/1334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/media\/1333"}],"wp:attachment":[{"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/media?parent=1332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/categories?post=1332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbanistes.be\/cub\/wp-json\/wp\/v2\/tags?post=1332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}